

{"id":5,"count":1,"description":"","link":"https:\/\/sites.temple.edu\/charlesclarkphysics\/category\/physics\/","name":"Physics","slug":"physics","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/sites.temple.edu\/charlesclarkphysics\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.temple.edu\/charlesclarkphysics\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sites.temple.edu\/charlesclarkphysics\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sites.temple.edu\/charlesclarkphysics\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}